{"id":629,"date":"2025-05-06T14:00:49","date_gmt":"2025-05-06T12:00:49","guid":{"rendered":"https:\/\/mercatdesantacatalina.com\/?p=629"},"modified":"2025-06-20T18:15:17","modified_gmt":"2025-06-20T16:15:17","slug":"fish-seafood-felix","status":"publish","type":"post","link":"https:\/\/mercatdesantacatalina.com\/en\/fish-seafood-felix\/","title":{"rendered":"Pescados &amp; Mariscos F\u00e9lix"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Contact Information<\/h2>\n\n\n\n<figure class=\"wp-block-table\"><table><tbody><tr><td><strong>Stalls<\/strong><\/td><td><a href=\"https:\/\/mercatdesantacatalina.com\/wp-content\/uploads\/2025\/06\/Ubica-ES-EcoillaCarnEco-PeixFelix-Arume3.gif\" target=\"_blank\" rel=\"noreferrer noopener\">101-105<\/a><\/td><\/tr><tr><td><strong>Tel.<\/strong><\/td><td><a href=\"tel:+34647418854\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">+34 647 418 854<\/a><\/td><\/tr><tr><td><strong>IG<\/strong><\/td><td><a href=\"https:\/\/www.instagram.com\/pescadosmariscosfelix\/\" target=\"_blank\" rel=\"noreferrer noopener\">@pescadosmariscosfelix<\/a><\/td><\/tr><tr><td><strong>FB<\/strong><\/td><td><a href=\"https:\/\/www.facebook.com\/Pescados-y-Mariscos-F\u00c9LIX-1436170570024645\" target=\"_blank\" rel=\"noreferrer noopener\">Pescados-y-Mariscos-F\u00c9LIX<\/a><\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Description<\/h2>\n\n\n\n<p>Singular market stall being present by Felix, who since the beginning of 2015 was the one in charge of it.<\/p>\n\n\n\n<p>You will find first quality fish and seafood captured at the Mallorcan and mainland Spain coast. Here you will be able to find the best of the different seas.<br>We want to highlight some varieties of fish: Sea bass, Sea Bream and Galician fish, Salmon from Norway, Red tuna, Cod fish and Turbot fish.<\/p>\n\n\n\n<p>In addition to that we want to highlight some seafood: Galician Mussels and the red prawn from Soller.<\/p>\n\n\n\n<p>With these ingredients you will be able to cook the best menus! Come if you want to surprise your guests.<\/p>\n\n\n\n<p><strong>Specialties<\/strong>: Sea bass fish, Sea bream fish and Galician Hake fish pincho.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Gallery<\/h2>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-2 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/mercatdesantacatalina.com\/wp-content\/uploads\/2025\/04\/Pescados-mariscos-Felix-210.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"683\" height=\"1024\" data-id=\"604\" src=\"https:\/\/mercatdesantacatalina.com\/wp-content\/uploads\/2025\/04\/Pescados-mariscos-Felix-210-683x1024.jpg\" alt=\"Pescados y Mariscos F\u00e9lix (Mercat Santa Catalina)\" class=\"wp-image-604\" srcset=\"https:\/\/mercatdesantacatalina.com\/wp-content\/uploads\/2025\/04\/Pescados-mariscos-Felix-210-683x1024.jpg 683w, https:\/\/mercatdesantacatalina.com\/wp-content\/uploads\/2025\/04\/Pescados-mariscos-Felix-210-200x300.jpg 200w, https:\/\/mercatdesantacatalina.com\/wp-content\/uploads\/2025\/04\/Pescados-mariscos-Felix-210-768x1152.jpg 768w, https:\/\/mercatdesantacatalina.com\/wp-content\/uploads\/2025\/04\/Pescados-mariscos-Felix-210-660x990.jpg 660w, https:\/\/mercatdesantacatalina.com\/wp-content\/uploads\/2025\/04\/Pescados-mariscos-Felix-210-1000x1500.jpg 1000w, https:\/\/mercatdesantacatalina.com\/wp-content\/uploads\/2025\/04\/Pescados-mariscos-Felix-210.jpg 1024w\" sizes=\"auto, (max-width: 683px) 100vw, 683px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/mercatdesantacatalina.com\/wp-content\/uploads\/2025\/04\/Pescados-mariscos-Felix-215.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"667\" data-id=\"607\" src=\"https:\/\/mercatdesantacatalina.com\/wp-content\/uploads\/2025\/04\/Pescados-mariscos-Felix-215.jpg\" alt=\"Pescados y Mariscos F\u00e9lix (Mercat Santa Catalina)\" class=\"wp-image-607\" srcset=\"https:\/\/mercatdesantacatalina.com\/wp-content\/uploads\/2025\/04\/Pescados-mariscos-Felix-215.jpg 1000w, https:\/\/mercatdesantacatalina.com\/wp-content\/uploads\/2025\/04\/Pescados-mariscos-Felix-215-300x200.jpg 300w, https:\/\/mercatdesantacatalina.com\/wp-content\/uploads\/2025\/04\/Pescados-mariscos-Felix-215-768x512.jpg 768w, https:\/\/mercatdesantacatalina.com\/wp-content\/uploads\/2025\/04\/Pescados-mariscos-Felix-215-660x440.jpg 660w, https:\/\/mercatdesantacatalina.com\/wp-content\/uploads\/2025\/04\/Pescados-mariscos-Felix-215-373x248.jpg 373w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/mercatdesantacatalina.com\/wp-content\/uploads\/2025\/04\/Pescados-mariscos-Felix-ANT-1.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" data-id=\"610\" src=\"https:\/\/mercatdesantacatalina.com\/wp-content\/uploads\/2025\/04\/Pescados-mariscos-Felix-ANT-1.jpg\" alt=\"Pescados y Mariscos F\u00e9lix (Mercat Santa Catalina)\" class=\"wp-image-610\" srcset=\"https:\/\/mercatdesantacatalina.com\/wp-content\/uploads\/2025\/04\/Pescados-mariscos-Felix-ANT-1.jpg 1024w, https:\/\/mercatdesantacatalina.com\/wp-content\/uploads\/2025\/04\/Pescados-mariscos-Felix-ANT-1-300x300.jpg 300w, https:\/\/mercatdesantacatalina.com\/wp-content\/uploads\/2025\/04\/Pescados-mariscos-Felix-ANT-1-150x150.jpg 150w, https:\/\/mercatdesantacatalina.com\/wp-content\/uploads\/2025\/04\/Pescados-mariscos-Felix-ANT-1-768x768.jpg 768w, https:\/\/mercatdesantacatalina.com\/wp-content\/uploads\/2025\/04\/Pescados-mariscos-Felix-ANT-1-660x660.jpg 660w, https:\/\/mercatdesantacatalina.com\/wp-content\/uploads\/2025\/04\/Pescados-mariscos-Felix-ANT-1-1000x1000.jpg 1000w, https:\/\/mercatdesantacatalina.com\/wp-content\/uploads\/2025\/04\/Pescados-mariscos-Felix-ANT-1-373x373.jpg 373w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/mercatdesantacatalina.com\/wp-content\/uploads\/2025\/04\/Pescados-mariscos-Felix-ANT-3.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"683\" height=\"1024\" data-id=\"616\" src=\"https:\/\/mercatdesantacatalina.com\/wp-content\/uploads\/2025\/04\/Pescados-mariscos-Felix-ANT-3-683x1024.jpg\" alt=\"Pescados y Mariscos F\u00e9lix (Mercat Santa Catalina)\" class=\"wp-image-616\" srcset=\"https:\/\/mercatdesantacatalina.com\/wp-content\/uploads\/2025\/04\/Pescados-mariscos-Felix-ANT-3-683x1024.jpg 683w, https:\/\/mercatdesantacatalina.com\/wp-content\/uploads\/2025\/04\/Pescados-mariscos-Felix-ANT-3-200x300.jpg 200w, https:\/\/mercatdesantacatalina.com\/wp-content\/uploads\/2025\/04\/Pescados-mariscos-Felix-ANT-3-768x1152.jpg 768w, https:\/\/mercatdesantacatalina.com\/wp-content\/uploads\/2025\/04\/Pescados-mariscos-Felix-ANT-3-660x990.jpg 660w, https:\/\/mercatdesantacatalina.com\/wp-content\/uploads\/2025\/04\/Pescados-mariscos-Felix-ANT-3-1000x1500.jpg 1000w, https:\/\/mercatdesantacatalina.com\/wp-content\/uploads\/2025\/04\/Pescados-mariscos-Felix-ANT-3.jpg 1024w\" sizes=\"auto, (max-width: 683px) 100vw, 683px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/mercatdesantacatalina.com\/wp-content\/uploads\/2025\/04\/Pescados-mariscos-Felix-ANT-2.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"810\" height=\"540\" data-id=\"613\" src=\"https:\/\/mercatdesantacatalina.com\/wp-content\/uploads\/2025\/04\/Pescados-mariscos-Felix-ANT-2.jpg\" alt=\"Pescados y Mariscos F\u00e9lix (Mercat Santa Catalina)\" class=\"wp-image-613\" srcset=\"https:\/\/mercatdesantacatalina.com\/wp-content\/uploads\/2025\/04\/Pescados-mariscos-Felix-ANT-2.jpg 810w, https:\/\/mercatdesantacatalina.com\/wp-content\/uploads\/2025\/04\/Pescados-mariscos-Felix-ANT-2-300x200.jpg 300w, https:\/\/mercatdesantacatalina.com\/wp-content\/uploads\/2025\/04\/Pescados-mariscos-Felix-ANT-2-768x512.jpg 768w, https:\/\/mercatdesantacatalina.com\/wp-content\/uploads\/2025\/04\/Pescados-mariscos-Felix-ANT-2-660x440.jpg 660w, https:\/\/mercatdesantacatalina.com\/wp-content\/uploads\/2025\/04\/Pescados-mariscos-Felix-ANT-2-373x248.jpg 373w\" sizes=\"auto, (max-width: 810px) 100vw, 810px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/mercatdesantacatalina.com\/wp-content\/uploads\/2025\/04\/Pescados-mariscos-Felix-ANT-4.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"619\" src=\"https:\/\/mercatdesantacatalina.com\/wp-content\/uploads\/2025\/04\/Pescados-mariscos-Felix-ANT-4.jpg\" alt=\"Pescados y Mariscos F\u00e9lix (Mercat Santa Catalina)\" class=\"wp-image-619\" srcset=\"https:\/\/mercatdesantacatalina.com\/wp-content\/uploads\/2025\/04\/Pescados-mariscos-Felix-ANT-4.jpg 1024w, https:\/\/mercatdesantacatalina.com\/wp-content\/uploads\/2025\/04\/Pescados-mariscos-Felix-ANT-4-300x200.jpg 300w, https:\/\/mercatdesantacatalina.com\/wp-content\/uploads\/2025\/04\/Pescados-mariscos-Felix-ANT-4-768x512.jpg 768w, https:\/\/mercatdesantacatalina.com\/wp-content\/uploads\/2025\/04\/Pescados-mariscos-Felix-ANT-4-660x440.jpg 660w, https:\/\/mercatdesantacatalina.com\/wp-content\/uploads\/2025\/04\/Pescados-mariscos-Felix-ANT-4-1000x667.jpg 1000w, https:\/\/mercatdesantacatalina.com\/wp-content\/uploads\/2025\/04\/Pescados-mariscos-Felix-ANT-4-373x248.jpg 373w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Stalls 101-105<\/p>\n","protected":false},"author":2,"featured_media":619,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[42,39],"tags":[],"class_list":["post-629","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fishmongers","category-stall"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pescados &amp; Mariscos F\u00e9lix - Mercat de Santa Catalina<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mercatdesantacatalina.com\/en\/fish-seafood-felix\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pescados &amp; Mariscos F\u00e9lix - Mercat de Santa Catalina\" \/>\n<meta property=\"og:description\" content=\"Stalls 101-105\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mercatdesantacatalina.com\/en\/fish-seafood-felix\/\" \/>\n<meta property=\"og:site_name\" content=\"Mercat de Santa Catalina\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/mercatsantacatalina\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-06T12:00:49+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-20T16:15:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mercatdesantacatalina.com\/wp-content\/uploads\/2025\/04\/Pescados-mariscos-Felix-ANT-4.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"683\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Mercat de Santa Catalina\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mercat de Santa Catalina\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/mercatdesantacatalina.com\\\/en\\\/fish-seafood-felix\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mercatdesantacatalina.com\\\/en\\\/fish-seafood-felix\\\/\"},\"author\":{\"name\":\"Mercat de Santa Catalina\",\"@id\":\"https:\\\/\\\/mercatdesantacatalina.com\\\/en\\\/#\\\/schema\\\/person\\\/f2dd5c6ee9b925c30cffdcf60aea95ff\"},\"headline\":\"Pescados &amp; Mariscos F\u00e9lix\",\"datePublished\":\"2025-05-06T12:00:49+00:00\",\"dateModified\":\"2025-06-20T16:15:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/mercatdesantacatalina.com\\\/en\\\/fish-seafood-felix\\\/\"},\"wordCount\":140,\"publisher\":{\"@id\":\"https:\\\/\\\/mercatdesantacatalina.com\\\/en\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/mercatdesantacatalina.com\\\/en\\\/fish-seafood-felix\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mercatdesantacatalina.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/Pescados-mariscos-Felix-ANT-4.jpg\",\"articleSection\":[\"Fishmongers\",\"Stalls\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mercatdesantacatalina.com\\\/en\\\/fish-seafood-felix\\\/\",\"url\":\"https:\\\/\\\/mercatdesantacatalina.com\\\/en\\\/fish-seafood-felix\\\/\",\"name\":\"Pescados &amp; Mariscos F\u00e9lix - Mercat de Santa Catalina\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mercatdesantacatalina.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mercatdesantacatalina.com\\\/en\\\/fish-seafood-felix\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mercatdesantacatalina.com\\\/en\\\/fish-seafood-felix\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mercatdesantacatalina.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/Pescados-mariscos-Felix-ANT-4.jpg\",\"datePublished\":\"2025-05-06T12:00:49+00:00\",\"dateModified\":\"2025-06-20T16:15:17+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mercatdesantacatalina.com\\\/en\\\/fish-seafood-felix\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mercatdesantacatalina.com\\\/en\\\/fish-seafood-felix\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/mercatdesantacatalina.com\\\/en\\\/fish-seafood-felix\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mercatdesantacatalina.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/Pescados-mariscos-Felix-ANT-4.jpg\",\"contentUrl\":\"https:\\\/\\\/mercatdesantacatalina.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/Pescados-mariscos-Felix-ANT-4.jpg\",\"width\":1024,\"height\":683,\"caption\":\"Pescados y Mariscos F\u00e9lix (Mercat Santa Catalina)\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mercatdesantacatalina.com\\\/en\\\/fish-seafood-felix\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/mercatdesantacatalina.com\\\/en\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pescados &amp; Mariscos F\u00e9lix\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mercatdesantacatalina.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/mercatdesantacatalina.com\\\/en\\\/\",\"name\":\"Mercat de Santa Catalina\",\"description\":\"Mercado municipal decano de Palma\",\"publisher\":{\"@id\":\"https:\\\/\\\/mercatdesantacatalina.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mercatdesantacatalina.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mercatdesantacatalina.com\\\/en\\\/#organization\",\"name\":\"Mercat de Santa Catalina\",\"url\":\"https:\\\/\\\/mercatdesantacatalina.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/mercatdesantacatalina.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mercatdesantacatalina.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Logo-Mercat-Santa-Catalina-1000px.png\",\"contentUrl\":\"https:\\\/\\\/mercatdesantacatalina.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Logo-Mercat-Santa-Catalina-1000px.png\",\"width\":1000,\"height\":1000,\"caption\":\"Mercat de Santa Catalina\"},\"image\":{\"@id\":\"https:\\\/\\\/mercatdesantacatalina.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/mercatsantacatalina\\\/\",\"https:\\\/\\\/www.instagram.com\\\/mercatdesantacatalina\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/mercatdesantacatalina.com\\\/en\\\/#\\\/schema\\\/person\\\/f2dd5c6ee9b925c30cffdcf60aea95ff\",\"name\":\"Mercat de Santa Catalina\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/795a64c0fdef9a073a2789bc748f43c21362dbab78e5889fa196f88e37df7b5d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/795a64c0fdef9a073a2789bc748f43c21362dbab78e5889fa196f88e37df7b5d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/795a64c0fdef9a073a2789bc748f43c21362dbab78e5889fa196f88e37df7b5d?s=96&d=mm&r=g\",\"caption\":\"Mercat de Santa Catalina\"},\"description\":\"Mercat municipal de Santa Catalina (Palma).\",\"sameAs\":[\"https:\\\/\\\/mercatdesantacatalina.com\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pescados &amp; Mariscos F\u00e9lix - Mercat de Santa Catalina","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mercatdesantacatalina.com\/en\/fish-seafood-felix\/","og_locale":"en_US","og_type":"article","og_title":"Pescados &amp; Mariscos F\u00e9lix - Mercat de Santa Catalina","og_description":"Stalls 101-105","og_url":"https:\/\/mercatdesantacatalina.com\/en\/fish-seafood-felix\/","og_site_name":"Mercat de Santa Catalina","article_publisher":"https:\/\/www.facebook.com\/mercatsantacatalina\/","article_published_time":"2025-05-06T12:00:49+00:00","article_modified_time":"2025-06-20T16:15:17+00:00","og_image":[{"width":1024,"height":683,"url":"https:\/\/mercatdesantacatalina.com\/wp-content\/uploads\/2025\/04\/Pescados-mariscos-Felix-ANT-4.jpg","type":"image\/jpeg"}],"author":"Mercat de Santa Catalina","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Mercat de Santa Catalina","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/mercatdesantacatalina.com\/en\/fish-seafood-felix\/#article","isPartOf":{"@id":"https:\/\/mercatdesantacatalina.com\/en\/fish-seafood-felix\/"},"author":{"name":"Mercat de Santa Catalina","@id":"https:\/\/mercatdesantacatalina.com\/en\/#\/schema\/person\/f2dd5c6ee9b925c30cffdcf60aea95ff"},"headline":"Pescados &amp; Mariscos F\u00e9lix","datePublished":"2025-05-06T12:00:49+00:00","dateModified":"2025-06-20T16:15:17+00:00","mainEntityOfPage":{"@id":"https:\/\/mercatdesantacatalina.com\/en\/fish-seafood-felix\/"},"wordCount":140,"publisher":{"@id":"https:\/\/mercatdesantacatalina.com\/en\/#organization"},"image":{"@id":"https:\/\/mercatdesantacatalina.com\/en\/fish-seafood-felix\/#primaryimage"},"thumbnailUrl":"https:\/\/mercatdesantacatalina.com\/wp-content\/uploads\/2025\/04\/Pescados-mariscos-Felix-ANT-4.jpg","articleSection":["Fishmongers","Stalls"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/mercatdesantacatalina.com\/en\/fish-seafood-felix\/","url":"https:\/\/mercatdesantacatalina.com\/en\/fish-seafood-felix\/","name":"Pescados &amp; Mariscos F\u00e9lix - Mercat de Santa Catalina","isPartOf":{"@id":"https:\/\/mercatdesantacatalina.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mercatdesantacatalina.com\/en\/fish-seafood-felix\/#primaryimage"},"image":{"@id":"https:\/\/mercatdesantacatalina.com\/en\/fish-seafood-felix\/#primaryimage"},"thumbnailUrl":"https:\/\/mercatdesantacatalina.com\/wp-content\/uploads\/2025\/04\/Pescados-mariscos-Felix-ANT-4.jpg","datePublished":"2025-05-06T12:00:49+00:00","dateModified":"2025-06-20T16:15:17+00:00","breadcrumb":{"@id":"https:\/\/mercatdesantacatalina.com\/en\/fish-seafood-felix\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mercatdesantacatalina.com\/en\/fish-seafood-felix\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/mercatdesantacatalina.com\/en\/fish-seafood-felix\/#primaryimage","url":"https:\/\/mercatdesantacatalina.com\/wp-content\/uploads\/2025\/04\/Pescados-mariscos-Felix-ANT-4.jpg","contentUrl":"https:\/\/mercatdesantacatalina.com\/wp-content\/uploads\/2025\/04\/Pescados-mariscos-Felix-ANT-4.jpg","width":1024,"height":683,"caption":"Pescados y Mariscos F\u00e9lix (Mercat Santa Catalina)"},{"@type":"BreadcrumbList","@id":"https:\/\/mercatdesantacatalina.com\/en\/fish-seafood-felix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/mercatdesantacatalina.com\/en\/home\/"},{"@type":"ListItem","position":2,"name":"Pescados &amp; Mariscos F\u00e9lix"}]},{"@type":"WebSite","@id":"https:\/\/mercatdesantacatalina.com\/en\/#website","url":"https:\/\/mercatdesantacatalina.com\/en\/","name":"Mercat de Santa Catalina","description":"Mercado municipal decano de Palma","publisher":{"@id":"https:\/\/mercatdesantacatalina.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mercatdesantacatalina.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/mercatdesantacatalina.com\/en\/#organization","name":"Mercat de Santa Catalina","url":"https:\/\/mercatdesantacatalina.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/mercatdesantacatalina.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/mercatdesantacatalina.com\/wp-content\/uploads\/2025\/05\/Logo-Mercat-Santa-Catalina-1000px.png","contentUrl":"https:\/\/mercatdesantacatalina.com\/wp-content\/uploads\/2025\/05\/Logo-Mercat-Santa-Catalina-1000px.png","width":1000,"height":1000,"caption":"Mercat de Santa Catalina"},"image":{"@id":"https:\/\/mercatdesantacatalina.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/mercatsantacatalina\/","https:\/\/www.instagram.com\/mercatdesantacatalina\/"]},{"@type":"Person","@id":"https:\/\/mercatdesantacatalina.com\/en\/#\/schema\/person\/f2dd5c6ee9b925c30cffdcf60aea95ff","name":"Mercat de Santa Catalina","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/795a64c0fdef9a073a2789bc748f43c21362dbab78e5889fa196f88e37df7b5d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/795a64c0fdef9a073a2789bc748f43c21362dbab78e5889fa196f88e37df7b5d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/795a64c0fdef9a073a2789bc748f43c21362dbab78e5889fa196f88e37df7b5d?s=96&d=mm&r=g","caption":"Mercat de Santa Catalina"},"description":"Mercat municipal de Santa Catalina (Palma).","sameAs":["https:\/\/mercatdesantacatalina.com\/"]}]}},"_links":{"self":[{"href":"https:\/\/mercatdesantacatalina.com\/en\/wp-json\/wp\/v2\/posts\/629","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mercatdesantacatalina.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mercatdesantacatalina.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mercatdesantacatalina.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/mercatdesantacatalina.com\/en\/wp-json\/wp\/v2\/comments?post=629"}],"version-history":[{"count":5,"href":"https:\/\/mercatdesantacatalina.com\/en\/wp-json\/wp\/v2\/posts\/629\/revisions"}],"predecessor-version":[{"id":6055,"href":"https:\/\/mercatdesantacatalina.com\/en\/wp-json\/wp\/v2\/posts\/629\/revisions\/6055"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mercatdesantacatalina.com\/en\/wp-json\/wp\/v2\/media\/619"}],"wp:attachment":[{"href":"https:\/\/mercatdesantacatalina.com\/en\/wp-json\/wp\/v2\/media?parent=629"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mercatdesantacatalina.com\/en\/wp-json\/wp\/v2\/categories?post=629"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mercatdesantacatalina.com\/en\/wp-json\/wp\/v2\/tags?post=629"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}