{"id":118,"count":5,"description":"","link":"https:\/\/mercatdesantacatalina.com\/en\/tag\/slide2_en\/","name":"slide2_en","slug":"slide2_en","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>slide2_en archivos - Mercat de Santa Catalina<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mercatdesantacatalina.com\/en\/tag\/slide2_en\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"slide2_en archivos - Mercat de Santa Catalina\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mercatdesantacatalina.com\/en\/tag\/slide2_en\/\" \/>\n<meta property=\"og:site_name\" content=\"Mercat de Santa Catalina\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/mercatdesantacatalina.com\\\/en\\\/tag\\\/slide2_en\\\/\",\"url\":\"https:\\\/\\\/mercatdesantacatalina.com\\\/en\\\/tag\\\/slide2_en\\\/\",\"name\":\"slide2_en archivos - Mercat de Santa Catalina\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mercatdesantacatalina.com\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mercatdesantacatalina.com\\\/en\\\/tag\\\/slide2_en\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mercatdesantacatalina.com\\\/en\\\/tag\\\/slide2_en\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/mercatdesantacatalina.com\\\/en\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"slide2_en\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mercatdesantacatalina.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/mercatdesantacatalina.com\\\/en\\\/\",\"name\":\"Mercat de Santa Catalina\",\"description\":\"Mercado municipal decano de Palma\",\"publisher\":{\"@id\":\"https:\\\/\\\/mercatdesantacatalina.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mercatdesantacatalina.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mercatdesantacatalina.com\\\/en\\\/#organization\",\"name\":\"Mercat de Santa Catalina\",\"url\":\"https:\\\/\\\/mercatdesantacatalina.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/mercatdesantacatalina.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mercatdesantacatalina.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Logo-Mercat-Santa-Catalina-1000px.png\",\"contentUrl\":\"https:\\\/\\\/mercatdesantacatalina.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Logo-Mercat-Santa-Catalina-1000px.png\",\"width\":1000,\"height\":1000,\"caption\":\"Mercat de Santa Catalina\"},\"image\":{\"@id\":\"https:\\\/\\\/mercatdesantacatalina.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/mercatsantacatalina\\\/\",\"https:\\\/\\\/www.instagram.com\\\/mercatdesantacatalina\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"slide2_en archivos - Mercat de Santa Catalina","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mercatdesantacatalina.com\/en\/tag\/slide2_en\/","og_locale":"en_US","og_type":"article","og_title":"slide2_en archivos - Mercat de Santa Catalina","og_url":"https:\/\/mercatdesantacatalina.com\/en\/tag\/slide2_en\/","og_site_name":"Mercat de Santa Catalina","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/mercatdesantacatalina.com\/en\/tag\/slide2_en\/","url":"https:\/\/mercatdesantacatalina.com\/en\/tag\/slide2_en\/","name":"slide2_en archivos - Mercat de Santa Catalina","isPartOf":{"@id":"https:\/\/mercatdesantacatalina.com\/en\/#website"},"breadcrumb":{"@id":"https:\/\/mercatdesantacatalina.com\/en\/tag\/slide2_en\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/mercatdesantacatalina.com\/en\/tag\/slide2_en\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/mercatdesantacatalina.com\/en\/home\/"},{"@type":"ListItem","position":2,"name":"slide2_en"}]},{"@type":"WebSite","@id":"https:\/\/mercatdesantacatalina.com\/en\/#website","url":"https:\/\/mercatdesantacatalina.com\/en\/","name":"Mercat de Santa Catalina","description":"Mercado municipal decano de Palma","publisher":{"@id":"https:\/\/mercatdesantacatalina.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mercatdesantacatalina.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/mercatdesantacatalina.com\/en\/#organization","name":"Mercat de Santa Catalina","url":"https:\/\/mercatdesantacatalina.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/mercatdesantacatalina.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/mercatdesantacatalina.com\/wp-content\/uploads\/2025\/05\/Logo-Mercat-Santa-Catalina-1000px.png","contentUrl":"https:\/\/mercatdesantacatalina.com\/wp-content\/uploads\/2025\/05\/Logo-Mercat-Santa-Catalina-1000px.png","width":1000,"height":1000,"caption":"Mercat de Santa Catalina"},"image":{"@id":"https:\/\/mercatdesantacatalina.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/mercatsantacatalina\/","https:\/\/www.instagram.com\/mercatdesantacatalina\/"]}]}},"_links":{"self":[{"href":"https:\/\/mercatdesantacatalina.com\/en\/wp-json\/wp\/v2\/tags\/118","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mercatdesantacatalina.com\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/mercatdesantacatalina.com\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/mercatdesantacatalina.com\/en\/wp-json\/wp\/v2\/posts?tags=118"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}